{"id":2073,"date":"2019-01-07T10:08:08","date_gmt":"2019-01-07T08:08:08","guid":{"rendered":"https:\/\/fracs.aero\/\/?p=2073"},"modified":"2021-09-27T16:17:53","modified_gmt":"2021-09-27T14:17:53","slug":"le-mot-du-directeur-2","status":"publish","type":"post","link":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/","title":{"rendered":"Le mot du directeur"},"content":{"rendered":"<p>DSNA Services vient de f\u00eater ses 5 ans d\u2019existence, cinq ann\u00e9es intenses faites de projets divers, de la reprise des espaces a\u00e9riens Soudanais mis en service en 2018 \u00e0 l\u2019assistance au d\u00e9veloppement de l\u2019Autorit\u00e9 de Surveillance Ha\u00eftienne, l\u2019OFNAC, qui entre dans une phase d\u00e9cisive, en passant par le d\u00e9veloppement d\u2019une solution de d\u00e9tection de drone, HOLOGARDE, d\u00e9montr\u00e9e au salon a\u00e9ronautique du Bourget 2017 et faisant aujourd\u2019hui l\u2019objet d\u2019une industrialisation. L\u2019actualit\u00e9 r\u00e9cente \u00e0 l\u2019a\u00e9roport de Gatwick est venue confirmer la pertinence de ce d\u00e9veloppement.<\/p>\n<p>Cinq ans, pour une soci\u00e9t\u00e9, c\u2019est la prime jeunesse ou l\u2019adolescence, et apr\u00e8s toutes ces premi\u00e8res exp\u00e9riences, il est sans doute n\u00e9cessaire de consolider les acquis et de construire un futur stabilis\u00e9 qui capitalise sur les diff\u00e9rentes initiatives heureuses et malheureuses de ces cinq premi\u00e8res ann\u00e9es d\u2019existence.<\/p>\n<p>L\u2019ann\u00e9e 2018 aura \u00e9t\u00e9 une ann\u00e9e de transition avec un changement de directeur \u00e0 la t\u00eate de DSNA Services mais aussi quelques changements au sein de l\u2019\u00e9quipe. 2019 devrait \u00eatre celle de la structuration et de la consolidation au travers de plusieurs axes:<\/p>\n<ul>\n<li>Une clarification de l\u2019identit\u00e9 du GIE DSNA Services;<\/li>\n<li>Une consolidation du catalogue des services offerts et la cr\u00e9ation de nouveaux services;<\/li>\n<li>Au sein de ses nouveaux locaux sur le campus ENAC, la mise en \u0153uvre de syst\u00e8mes d\u2019information modernes;<\/li>\n<li>La consolidation et le d\u00e9veloppement des partenariats; et enfin,<\/li>\n<li>Le renforcement significatif de l\u2019\u00e9quipe.<\/li>\n<\/ul>\n<p>DSNA Services ne serait rien sans les nombreux experts de la DGAC et de l\u2019ENAC qui viennent lui pr\u00eater main forte au fil des projets. Tous font partie d\u2019une m\u00eame communaut\u00e9 destin\u00e9e \u00e0 valoriser le savoir-faire de l\u2019Aviation Civile fran\u00e7aise dans le monde. Je souhaite ici les remercier pour leur engagement. Des initiatives seront lanc\u00e9es \u00e0 destination des experts et des services DGAC afin de conforter l\u2019esprit de partage et d\u2019\u00e9quipe qui nous anime.<\/p>\n<p>Parmi les axes strat\u00e9giques de l\u2019ann\u00e9e 2019, figure le d\u00e9veloppement d\u2019une strat\u00e9gie pour placer DSNA Services comme un soutien essentiel au d\u00e9ploiement et \u00e0 la mise en \u0153uvre des standards OACI dans le monde. Le projet de renforcement de l\u2019Autorit\u00e9 de Surveillance Ha\u00eftienne devrait, je l\u2019esp\u00e8re, en \u00eatre un bel exemple. Ce sera \u00e9galement le cas du d\u00e9veloppement de nouveaux services visant \u00e0 assister les Autorit\u00e9s de l\u2019Aviation Civile dans la mise en \u0153uvre de leurs obligations.<\/p>\n<p>En conclusion, je souhaite ici remercier tous ceux qui ont contribu\u00e9 en 2018 aux succ\u00e8s de nos projets\u00a0: experts, clients, PME, Grands groupes, services DGAC et ENAC et enfin tous les membres de l\u2019\u00e9quipe des DSNA Services. 2019 sera l\u2019occasion de r\u00e9affirmer encore nos valeurs et notre ambition de servir le d\u00e9veloppement s\u00fbr, s\u00e9curitaire et durable de l\u2019aviation civile dans le monde.<\/p>\n<p>Je vous souhaite \u00e0 tous ainsi qu\u2019\u00e0 tous les v\u00f4tres une excellente ann\u00e9e 2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DSNA Services vient de f\u00eater ses 5 ans d\u2019existence, cinq ann\u00e9es intenses faites de projets divers, de la reprise des espaces a\u00e9riens Soudanais mis en service en 2018 \u00e0 l\u2019assistance au d\u00e9veloppement de l\u2019Autorit\u00e9 de Surveillance Ha\u00eftienne, l\u2019OFNAC, qui entre dans une phase d\u00e9cisive, en passant par le d\u00e9veloppement d\u2019une solution de d\u00e9tection de drone, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2071,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[25],"tags":[],"class_list":["post-2073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le mot du directeur - France Aviation Civile Services<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le mot du directeur - France Aviation Civile Services\" \/>\n<meta property=\"og:description\" content=\"DSNA Services vient de f\u00eater ses 5 ans d\u2019existence, cinq ann\u00e9es intenses faites de projets divers, de la reprise des espaces a\u00e9riens Soudanais mis en service en 2018 \u00e0 l\u2019assistance au d\u00e9veloppement de l\u2019Autorit\u00e9 de Surveillance Ha\u00eftienne, l\u2019OFNAC, qui entre dans une phase d\u00e9cisive, en passant par le d\u00e9veloppement d\u2019une solution de d\u00e9tection de drone, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/\" \/>\n<meta property=\"og:site_name\" content=\"France Aviation Civile Services\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-07T08:08:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-27T14:17:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fracs.aero\/wp-content\/uploads\/2019\/01\/entete_articles_motdirecteur.png\" \/>\n\t<meta property=\"og:image:width\" content=\"705\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin_c4com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fracsaero\" \/>\n<meta name=\"twitter:site\" content=\"@fracsaero\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_c4com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/\"},\"author\":{\"name\":\"admin_c4com\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#\\\/schema\\\/person\\\/3222c26523ed0e5e952220f697e48267\"},\"headline\":\"Le mot du directeur\",\"datePublished\":\"2019-01-07T08:08:08+00:00\",\"dateModified\":\"2021-09-27T14:17:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fracs.aero\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/entete_articles_motdirecteur.png\",\"articleSection\":[\"ACTUALIT\u00c9S\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/\",\"url\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/\",\"name\":\"Le mot du directeur - France Aviation Civile Services\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fracs.aero\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/entete_articles_motdirecteur.png\",\"datePublished\":\"2019-01-07T08:08:08+00:00\",\"dateModified\":\"2021-09-27T14:17:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fracs.aero\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/entete_articles_motdirecteur.png\",\"contentUrl\":\"https:\\\/\\\/fracs.aero\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/entete_articles_motdirecteur.png\",\"width\":705,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/2019\\\/01\\\/07\\\/le-mot-du-directeur-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le mot du directeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/\",\"name\":\"France Aviation Civile Services\",\"description\":\"France Aviation Civile Services\",\"publisher\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#organization\",\"name\":\"France Aviation Civile Services\",\"url\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fracs.aero\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/FRACS-for-web-1.png\",\"contentUrl\":\"https:\\\/\\\/fracs.aero\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/FRACS-for-web-1.png\",\"width\":340,\"height\":156,\"caption\":\"France Aviation Civile Services\"},\"image\":{\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/fracsaero\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fracs\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/#\\\/schema\\\/person\\\/3222c26523ed0e5e952220f697e48267\",\"name\":\"admin_c4com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57dfc6b92119c0d9c4ea846b9365edd591c6c8ab72c7637242b68295f8b6eb36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57dfc6b92119c0d9c4ea846b9365edd591c6c8ab72c7637242b68295f8b6eb36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57dfc6b92119c0d9c4ea846b9365edd591c6c8ab72c7637242b68295f8b6eb36?s=96&d=mm&r=g\",\"caption\":\"admin_c4com\"},\"url\":\"https:\\\/\\\/fracs.aero\\\/fr\\\/author\\\/admin_c4com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le mot du directeur - France Aviation Civile Services","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Le mot du directeur - France Aviation Civile Services","og_description":"DSNA Services vient de f\u00eater ses 5 ans d\u2019existence, cinq ann\u00e9es intenses faites de projets divers, de la reprise des espaces a\u00e9riens Soudanais mis en service en 2018 \u00e0 l\u2019assistance au d\u00e9veloppement de l\u2019Autorit\u00e9 de Surveillance Ha\u00eftienne, l\u2019OFNAC, qui entre dans une phase d\u00e9cisive, en passant par le d\u00e9veloppement d\u2019une solution de d\u00e9tection de drone, [&hellip;]","og_url":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/","og_site_name":"France Aviation Civile Services","article_published_time":"2019-01-07T08:08:08+00:00","article_modified_time":"2021-09-27T14:17:53+00:00","og_image":[{"width":705,"height":300,"url":"https:\/\/fracs.aero\/wp-content\/uploads\/2019\/01\/entete_articles_motdirecteur.png","type":"image\/png"}],"author":"admin_c4com","twitter_card":"summary_large_image","twitter_creator":"@fracsaero","twitter_site":"@fracsaero","twitter_misc":{"\u00c9crit par":"admin_c4com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/#article","isPartOf":{"@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/"},"author":{"name":"admin_c4com","@id":"https:\/\/fracs.aero\/fr\/#\/schema\/person\/3222c26523ed0e5e952220f697e48267"},"headline":"Le mot du directeur","datePublished":"2019-01-07T08:08:08+00:00","dateModified":"2021-09-27T14:17:53+00:00","mainEntityOfPage":{"@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/"},"wordCount":520,"publisher":{"@id":"https:\/\/fracs.aero\/fr\/#organization"},"image":{"@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fracs.aero\/wp-content\/uploads\/2019\/01\/entete_articles_motdirecteur.png","articleSection":["ACTUALIT\u00c9S"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/","url":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/","name":"Le mot du directeur - France Aviation Civile Services","isPartOf":{"@id":"https:\/\/fracs.aero\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/#primaryimage"},"image":{"@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fracs.aero\/wp-content\/uploads\/2019\/01\/entete_articles_motdirecteur.png","datePublished":"2019-01-07T08:08:08+00:00","dateModified":"2021-09-27T14:17:53+00:00","breadcrumb":{"@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/#primaryimage","url":"https:\/\/fracs.aero\/wp-content\/uploads\/2019\/01\/entete_articles_motdirecteur.png","contentUrl":"https:\/\/fracs.aero\/wp-content\/uploads\/2019\/01\/entete_articles_motdirecteur.png","width":705,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/fracs.aero\/fr\/2019\/01\/07\/le-mot-du-directeur-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fracs.aero\/fr\/"},{"@type":"ListItem","position":2,"name":"Le mot du directeur"}]},{"@type":"WebSite","@id":"https:\/\/fracs.aero\/fr\/#website","url":"https:\/\/fracs.aero\/fr\/","name":"France Aviation Civile Services","description":"France Aviation Civile Services","publisher":{"@id":"https:\/\/fracs.aero\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fracs.aero\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fracs.aero\/fr\/#organization","name":"France Aviation Civile Services","url":"https:\/\/fracs.aero\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fracs.aero\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fracs.aero\/wp-content\/uploads\/2019\/08\/FRACS-for-web-1.png","contentUrl":"https:\/\/fracs.aero\/wp-content\/uploads\/2019\/08\/FRACS-for-web-1.png","width":340,"height":156,"caption":"France Aviation Civile Services"},"image":{"@id":"https:\/\/fracs.aero\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/fracsaero","https:\/\/www.linkedin.com\/company\/fracs\/"]},{"@type":"Person","@id":"https:\/\/fracs.aero\/fr\/#\/schema\/person\/3222c26523ed0e5e952220f697e48267","name":"admin_c4com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57dfc6b92119c0d9c4ea846b9365edd591c6c8ab72c7637242b68295f8b6eb36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57dfc6b92119c0d9c4ea846b9365edd591c6c8ab72c7637242b68295f8b6eb36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57dfc6b92119c0d9c4ea846b9365edd591c6c8ab72c7637242b68295f8b6eb36?s=96&d=mm&r=g","caption":"admin_c4com"},"url":"https:\/\/fracs.aero\/fr\/author\/admin_c4com\/"}]}},"_links":{"self":[{"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/posts\/2073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/comments?post=2073"}],"version-history":[{"count":0,"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/posts\/2073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/media\/2071"}],"wp:attachment":[{"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/media?parent=2073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/categories?post=2073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fracs.aero\/fr\/wp-json\/wp\/v2\/tags?post=2073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}